{"id":24841,"date":"2013-08-20T06:55:21","date_gmt":"2013-08-20T06:55:21","guid":{"rendered":"https:\/\/wordpress.org\/plugins-wp\/lb-select-location\/"},"modified":"2014-02-24T16:38:13","modified_gmt":"2014-02-24T16:38:13","slug":"lb-select-location","status":"publish","type":"plugin","link":"https:\/\/szl.wordpress.org\/plugins\/lb-select-location\/","author":12972120,"comment_status":"closed","ping_status":"closed","template":"","meta":{"version":"2.6.1","stable_tag":"2.6.2","tested":"3.6.1","requires":"3.6","requires_php":"","requires_plugins":"","header_name":"LB Select location","header_author":"Luca Bonaldo","header_description":"","assets_banners_color":"","last_updated":"2014-02-24 16:38:13","external_support_url":"","external_repository_url":"","donate_link":"","header_plugin_uri":"http:\/\/www.lucabonaldo.it\/lb-select-location-plugin\/","header_author_uri":"http:\/\/www.lucabonaldo.it","rating":5,"author_block_rating":0,"active_installs":10,"downloads":3098,"num_ratings":1,"support_threads":0,"support_threads_resolved":0,"author_block_count":0,"sections":["description","installation"],"tags":[],"upgrade_notice":[],"ratings":{"1":0,"2":0,"3":0,"4":0,"5":"1"},"assets_icons":[],"assets_banners":[],"assets_blueprints":{},"all_blocks":[],"tagged_versions":["2.6.0","2.6.1","2.6.2"],"block_files":[],"assets_screenshots":{"screenshot-1.png":{"filename":"screenshot-1.png","revision":"759765","resolution":"1","location":"assets","width":520,"height":270},"screenshot-2.png":{"filename":"screenshot-2.png","revision":"759765","resolution":"2","location":"assets","width":1368,"height":604}},"screenshots":{"1":"<p>Descrizione visuale degli attributi opzionali dello shortcode.<\/p>","2":"<p>Esempio d'uso in un custom post type.<\/p>"}},"plugin_section":[],"plugin_tags":[7031,27662,39879,39878,39877],"plugin_category":[],"plugin_contributors":[92083],"plugin_business_model":[],"class_list":["post-24841","plugin","type-plugin","status-publish","hentry","plugin_tags-comuni","plugin_tags-italia","plugin_tags-province","plugin_tags-regioni","plugin_tags-selezione","plugin_contributors-bonny85","plugin_committers-bonny85"],"banners":[],"icons":{"svg":false,"icon":"https:\/\/s.w.org\/plugins\/geopattern-icon\/lb-select-location.svg","icon_2x":false,"generated":true},"screenshots":[{"src":"https:\/\/ps.w.org\/lb-select-location\/assets\/screenshot-1.png?rev=759765","caption":"<p>Descrizione visuale degli attributi opzionali dello shortcode.<\/p>"},{"src":"https:\/\/ps.w.org\/lb-select-location\/assets\/screenshot-2.png?rev=759765","caption":"<p>Esempio d'uso in un custom post type.<\/p>"}],"raw_content":"<!--section=description-->\n<p>LB Select Location permette di aggiungere al vostro blog, una select multipla a cascata per la selezione di una regione, provincia, comune d'Italia mediante uno shortcode. Inoltre il plugin mette a disposizione delle API per interagire con la base di dati e per selezionare dei valori predefiniti nelle select.<\/p>\n\n<p><strong>Instance:<\/strong> [lb-sl]<\/p>\n\n<ul>\n<li><em>form<\/em>: (default \"1\") valore identificativo per le select, utile (consigliato) se ci sono pi\u00f9 select nella pagine e per identificare le select dopo un POST o GET di una form contenente le select. <\/li>\n<li><em>province<\/em>: (default \"nome\") definisce l\u2019attributo delle province da visualizzare nella select province, i valori possibili sono nome e sigla o entrambi separati dal carattere \"&amp;\" (es: \"sigla&amp;nome\"), in questo caso gli attributi verranno visualizzati in questo modo \"sigla \u2013 nome\" (es: \"TO \u2013 Torino\" ). <\/li>\n<li><em>comuni<\/em>: (default \"nome\") definisce l\u2019attributo dei comuni da visualizzare nella select comuni, i valori possibili sono nome e cap  o entrambi separati dal carattere \"&amp;\" (es: \"cap&amp;nome\"), anche in questo caso verranno visualizzati in questo modo \"cap \u2013 nome\" (es: \"73100 - Lecce\") <\/li>\n<li><em>label_regioni<\/em>: (default \"Scegli \u2026\") definisce il valore di default della select regioni. <\/li>\n<li><em>label_province<\/em>: (default \"Scegli \u2026\") definisce il valore valore di default della select province. <\/li>\n<li><em>label_comuni<\/em>: (default \"Scegli \u2026\") definisce il valore valore di default della select comuni. <\/li>\n<li><em>text_regioni<\/em>: (default \"Regione\") definisce il valore valore per la label affianco alla select regioni. <\/li>\n<li><em>text_province<\/em>: (default \"Provincia\") definisce il valore valore per la label affianco alla select province. <\/li>\n<li><em>text_ comuni<\/em>: (default \"Comune\") definisce il valore valore per la label affianco alla select comuni. <\/li>\n<\/ul>\n\n<p>Esempio di shortcode:  [lb-sl  province=\"sigla&amp;nome\"]<\/p>\n\n<p><strong>API Reference<\/strong><\/p>\n\n<p><em>Select<\/em>  Class<\/p>\n\n<p>Implementa una suite di funzioni per interagire con la basi di dati (aggiornato a fine 2012), in particolare le tabelle regioni, province, comuni.<\/p>\n\n<p><em>Select_Load<\/em>   Class<\/p>\n\n<p>Implementa un metodo <em>populate()<\/em> per selezionare dei valori predefiniti nelle select. Per esempio se si usa il plugin per aggiungere un campo opzionale al profilo utente, \u201cluogo di nascita\u201d, dopo in primo salvataggio di tale informazione negli update successivi l\u2019utente dovr\u00e0 visualizzare le informazioni che si erano selezionate la volta prima.<\/p>\n\n<p><a href=\"http:\/\/www.lucabonaldo.it\/lb-select-location%EF%BB%BF%EF%BB%BF-plugin\/\">Documentation and example using<\/a><\/p>\n\n<p><a href=\"http:\/\/lucabonaldo.it\/plugin-docs\/lb-select-location-doc\/\">Source doce documentation here<\/a><\/p>\n\n<!--section=installation-->\n<ol>\n<li>Upload LB-Select-Location nella directory <code>\/wp-content\/plugins\/<\/code> <\/li>\n<li>Attivare il plugin tramite il menu 'Plugins' in WordPress<\/li>\n<li>Posizionere gli shortcode in qualsiasi post o page, ecc.<\/li>\n<\/ol>\n\n<p><strong>Per l'installazione multisito attivare il plugin nella rete.<\/strong><\/p>","raw_excerpt":"LB Select Location permette di aggiungere al vostro blog, una select multipla a cascata per la selezione di una regione, provincia, comune d\u2019Italia.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin\/24841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin"}],"about":[{"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/types\/plugin"}],"replies":[{"embeddable":true,"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/comments?post=24841"}],"author":[{"embeddable":true,"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wporg\/v1\/users\/bonny85"}],"wp:attachment":[{"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/media?parent=24841"}],"wp:term":[{"taxonomy":"plugin_section","embeddable":true,"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_section?post=24841"},{"taxonomy":"plugin_tags","embeddable":true,"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_tags?post=24841"},{"taxonomy":"plugin_category","embeddable":true,"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_category?post=24841"},{"taxonomy":"plugin_contributors","embeddable":true,"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_contributors?post=24841"},{"taxonomy":"plugin_business_model","embeddable":true,"href":"https:\/\/szl.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_business_model?post=24841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}